
{"id":7840,"date":"2023-10-05T14:20:55","date_gmt":"2023-10-05T12:20:55","guid":{"rendered":"https:\/\/barrelkings.s3.kersvers.cloud\/bestellung-stornieren\/"},"modified":"2026-07-02T12:57:49","modified_gmt":"2026-07-02T10:57:49","slug":"bestellung-stornieren","status":"publish","type":"page","link":"https:\/\/barrelkings.com\/de\/bestellung-stornieren\/","title":{"rendered":"Bestellung stornieren"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7840\" class=\"elementor elementor-7840 elementor-1378\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f7eae7e e-flex e-con-boxed e-con e-parent\" data-id=\"4f7eae7e\" data-element_type=\"container\" data-e-type=\"container\" id=\"toc\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4d5e2d15 e-con-full e-flex e-con e-child\" data-id=\"4d5e2d15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-731dec6a elementor-widget elementor-widget-heading\" data-id=\"731dec6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Bestellung stornieren<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be30950 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"be30950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc9dd12 elementor-widget elementor-widget-text-editor\" data-id=\"4bc9dd12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie haben das Recht, binnen 14 Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen.<\/p><p>Die Widerrufsfrist betr\u00e4gt 14 Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die letzte Ware in Besitz genommen haben bzw. hat.<\/p><p>Om uw herroepingsrecht uit te oefenen, moet u ons (Barrelkings, Daalderweg 20, 1507 DT Zaandam, info@barrelkings.com, telefoonnummer: +31 (0) 75 &#8211; 207 3027) door middel van een duidelijke verklaring (bijv. een brief per post, fax of e-mail) op de hoogte stellen van uw besluit om deze overeenkomst te herroepen. Sie k\u00f6nnen daf\u00fcr das beigef\u00fcgte Muster-Widerrufsformular verwenden, das jedoch nicht vorgeschrieben ist.<\/p><p>Zur Wahrung der Widerrufsfrist reicht es aus, dass Sie die Mitteilung \u00fcber die Aus\u00fcbung des Widerrufsrechts vor Ablauf der Widerrufsfrist absenden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21aac5fc elementor-widget elementor-widget-heading\" data-id=\"21aac5fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Folgen des Verfalls\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-520e87e3 elementor-widget elementor-widget-text-editor\" data-id=\"520e87e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie diesen Vertrag widerrufen, haben wir Ihnen alle Zahlungen, die wir von Ihnen erhalten haben, einschlie\u00dflich der Lieferkosten (mit Ausnahme der zus\u00e4tzlichen Kosten, die sich daraus ergeben, dass Sie eine andere Art der Lieferung als die von uns angebotene, g\u00fcnstigste Standardlieferung gew\u00e4hlt haben), unverz\u00fcglich und sp\u00e4testens binnen 14 Tagen ab dem Tag zur\u00fcckzuzahlen, an dem die Mitteilung \u00fcber Ihren Widerruf dieses Vertrags bei uns eingegangen ist. F\u00fcr diese R\u00fcckzahlung verwenden wir dasselbe Zahlungsmittel, das Sie bei der urspr\u00fcnglichen Transaktion eingesetzt haben, es sei denn, mit Ihnen wurde ausdr\u00fccklich etwas anderes vereinbart; in keinem Fall werden Ihnen wegen dieser R\u00fcckzahlung Entgelte berechnet. Wir k\u00f6nnen die R\u00fcckzahlung verweigern, bis wir die Waren wieder zur\u00fcckerhalten haben oder bis Sie den Nachweis erbracht haben, dass Sie die Waren zur\u00fcckgesandt haben, je nachdem, welches der fr\u00fchere Zeitpunkt ist.<\/p><p>Sie haben die Waren unverz\u00fcglich und in jedem Fall sp\u00e4testens binnen vierzehn Tagen ab dem Tag, an dem Sie uns \u00fcber den Widerruf dieses Vertrags unterrichten, an uns zur\u00fcckzusenden oder zu \u00fcbergeben. Die Frist ist gewahrt, wenn Sie die Waren vor Ablauf der 14-Tage-Frist versenden. Sie sind lediglich f\u00fcr die Kosten des R\u00fccktransports von Ihrer Wohnadresse zum Gesch\u00e4ft verantwortlich. Diese Kosten belaufen sich auf etwa 10 Euro pro Paket, die genauen Preise finden Sie auf der Website Ihres Transportunternehmens.<\/p><p>Das Widerrufsrecht besteht nicht, es sei denn, die Parteien haben etwas anderes vereinbart, bei folgenden Vertr\u00e4gen: Vertr\u00e4gen \u00fcber die Lieferung von Waren, die nicht vorgefertigt sind und f\u00fcr deren Herstellung eine individuelle Auswahl oder Bestimmung durch den Verbraucher ma\u00dfgeblich ist oder die eindeutig auf die pers\u00f6nlichen Bed\u00fcrfnisse des Verbrauchers zugeschnitten sind.<\/p><p><strong>Produktaustausch?<\/strong><\/p><p>M\u00f6chten Sie Ihr Produkt umtauschen? Das ist \u00fcberhaupt kein Problem. Sie k\u00f6nnen sich zu diesem Zweck an <a href=\"mailto:info@barrelkings.com\">info@barrelkings.com<\/a> wenden. Die Kosten f\u00fcr die R\u00fccksendung des Produkts tragen Sie jedoch selbst. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7219a4 elementor-widget elementor-widget-button\" data-id=\"f7219a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MTg0MTEsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Bestellung widerrufen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bestellung stornieren Sie haben das Recht, binnen 14 Tagen ohne Angabe von Gr\u00fcnden diesen Vertrag zu widerrufen. Die Widerrufsfrist betr\u00e4gt 14 Tage ab dem Tag, an dem Sie oder ein von Ihnen benannter Dritter, der nicht der Bef\u00f6rderer ist, die letzte Ware in Besitz genommen haben bzw. hat. Om uw herroepingsrecht uit te oefenen, moet [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7840","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/pages\/7840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/comments?post=7840"}],"version-history":[{"count":10,"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/pages\/7840\/revisions"}],"predecessor-version":[{"id":18428,"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/pages\/7840\/revisions\/18428"}],"wp:attachment":[{"href":"https:\/\/barrelkings.com\/de\/wp-json\/wp\/v2\/media?parent=7840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}